{"id":5867,"date":"2017-11-25T14:15:34","date_gmt":"2017-11-25T14:15:34","guid":{"rendered":"https:\/\/jukesales.nl:8080\/?post_type=product&#038;p=5867"},"modified":"2022-03-28T11:19:44","modified_gmt":"2022-03-28T11:19:44","slug":"wurlitzer-1650-service-manual","status":"publish","type":"product","link":"https:\/\/jukesales.nl\/nl\/shop\/parts\/wurlitzer-parts\/wurlitzer-1500-and-1600-series-wurlitzer-parts\/wurlitzer-1650-service-manual\/","title":{"rendered":"Wurlitzer 1650 Service Manual"},"content":{"rendered":"<p>Wurlitzer 1650 Service Manual<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wurlitzer 1650 Service Manual<\/p>\n","protected":false},"featured_media":5852,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_cat":[120,229],"product_tag":[],"class_list":{"0":"post-5867","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-wurlitzer-1500-and-1600-series-wurlitzer-parts","7":"product_cat-service-manuals","8":"product_shipping_class-briefpak","9":"col","11":"first","12":"outofstock","13":"taxable","14":"shipping-taxable","15":"purchasable","16":"product-type-simple"},"translation":{"provider":"WPGlobus","version":"3.0.0","language":"nl","enabled_languages":["en","nl","es","de","fr"],"languages":{"en":{"title":true,"content":true,"excerpt":false},"nl":{"title":false,"content":false,"excerpt":false},"es":{"title":false,"content":false,"excerpt":false},"de":{"title":false,"content":false,"excerpt":false},"fr":{"title":false,"content":false,"excerpt":false}}},"_links":{"self":[{"href":"https:\/\/jukesales.nl\/nl\/wp-json\/wp\/v2\/product\/5867","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jukesales.nl\/nl\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/jukesales.nl\/nl\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/jukesales.nl\/nl\/wp-json\/wp\/v2\/comments?post=5867"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jukesales.nl\/nl\/wp-json\/wp\/v2\/media\/5852"}],"wp:attachment":[{"href":"https:\/\/jukesales.nl\/nl\/wp-json\/wp\/v2\/media?parent=5867"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/jukesales.nl\/nl\/wp-json\/wp\/v2\/product_cat?post=5867"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/jukesales.nl\/nl\/wp-json\/wp\/v2\/product_tag?post=5867"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}