{"id":10742,"date":"2025-03-04T18:08:04","date_gmt":"2025-03-04T17:08:04","guid":{"rendered":"https:\/\/jukesales.nl\/?post_type=product&#038;p=10742"},"modified":"2025-03-04T18:08:05","modified_gmt":"2025-03-04T17:08:05","slug":"voeding-wurlitzer-18-t-m-2250-incl-55v","status":"publish","type":"product","link":"https:\/\/jukesales.nl\/es\/shop\/parts\/wurlitzer-parts\/wurlitzer-1800-wurlitzer-parts-parts\/voeding-wurlitzer-18-t-m-2250-incl-55v\/","title":{"rendered":"voeding Wurlitzer 18 t\/m 2250, incl 5,5V"},"content":{"rendered":"<p>voeding Wurlitzer 18 t\/m 2250, incl 5,5V<\/p>\n<p>perfect fit,<\/p>\n","protected":false},"excerpt":{"rendered":"<p>voeding Wurlitzer 18 t\/m 2250, incl 5,5V perfect fit,<\/p>\n","protected":false},"featured_media":10744,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_cat":[123,124,126,128,129,211],"product_tag":[],"class_list":{"0":"post-10742","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-wurlitzer-1800-wurlitzer-parts-parts","7":"product_cat-wurlitzer-1900-wurlitzer-parts","8":"product_cat-wurlitzer-2000-wurlitzer-parts","9":"product_cat-wurlitzer-2100-2104-2150-wurlitzer-parts","10":"product_cat-wurlitzer-2200-2204-2250-wurlitzer-parts","11":"product_cat-new-products","12":"product_shipping_class-pakket-tm-2kg","13":"col","15":"first","16":"instock","17":"taxable","18":"shipping-taxable","19":"purchasable","20":"product-type-simple"},"translation":{"provider":"WPGlobus","version":"3.0.0","language":"es","enabled_languages":["en","nl","es","de","fr"],"languages":{"en":{"title":true,"content":true,"excerpt":false},"nl":{"title":false,"content":false,"excerpt":false},"es":{"title":false,"content":false,"excerpt":false},"de":{"title":false,"content":false,"excerpt":false},"fr":{"title":false,"content":false,"excerpt":false}}},"_links":{"self":[{"href":"https:\/\/jukesales.nl\/es\/wp-json\/wp\/v2\/product\/10742","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jukesales.nl\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/jukesales.nl\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/jukesales.nl\/es\/wp-json\/wp\/v2\/comments?post=10742"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jukesales.nl\/es\/wp-json\/wp\/v2\/media\/10744"}],"wp:attachment":[{"href":"https:\/\/jukesales.nl\/es\/wp-json\/wp\/v2\/media?parent=10742"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/jukesales.nl\/es\/wp-json\/wp\/v2\/product_cat?post=10742"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/jukesales.nl\/es\/wp-json\/wp\/v2\/product_tag?post=10742"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}